{"id":3218,"date":"2022-05-10T10:25:40","date_gmt":"2022-05-10T08:25:40","guid":{"rendered":"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8.jpg"},"modified":"2022-05-10T10:25:40","modified_gmt":"2022-05-10T08:25:40","slug":"8-2","status":"inherit","type":"attachment","link":"https:\/\/gedenkstaette-vaihingen.de\/pl\/8-2\/","title":{"rendered":"8"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-3218","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"320\" src=\"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-480x320.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-480x320.jpg 480w, https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-1200x800.jpg 1200w, https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-768x512.jpg 768w, https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-1536x1024.jpg 1536w, https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-2048x1365.jpg 2048w, https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Vaihingen KZ Gedenkst\u2030tte im Wiesengrund . Auf einem Steg \u00b8ber den Fundamenten der Entlausungsbaracke stehen die Besucher und sehen die Filminstallation \/ad<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1707,"file":"2022\/05\/8-scaled.jpg","sizes":{"medium":{"file":"8-480x320.jpg","width":"480","height":"320","mime_type":"image\/jpeg","source_url":"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-480x320.jpg"},"large":{"file":"8-1200x800.jpg","width":"1200","height":"800","mime_type":"image\/jpeg","source_url":"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-1200x800.jpg"},"thumbnail":{"file":"8-150x150.jpg","width":"150","height":"150","mime_type":"image\/jpeg","source_url":"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-150x150.jpg"},"medium_large":{"file":"8-768x512.jpg","width":"768","height":"512","mime_type":"image\/jpeg","source_url":"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-768x512.jpg"},"1536x1536":{"file":"8-1536x1024.jpg","width":"1536","height":"1024","mime_type":"image\/jpeg","source_url":"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-1536x1024.jpg"},"2048x2048":{"file":"8-2048x1365.jpg","width":"2048","height":"1365","mime_type":"image\/jpeg","source_url":"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-2048x1365.jpg"},"bundlebee_one_hd":{"file":"8-1920x1280.jpg","width":"1920","height":"1280","mime_type":"image\/jpeg","source_url":"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-1920x1280.jpg"},"full":{"file":"8-scaled.jpg","width":2560,"height":1707,"mime_type":"image\/jpeg","source_url":"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"Drossel","camera":"","caption":"Vaihingen KZ Gedenkst\u2030tte im Wiesengrund . Auf einem Steg \u00b8ber den Fundamenten der Entlausungsbaracke stehen die Besucher und sehen die Filminstallation \/ad","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1"},"original_image":"8.jpg"},"post":null,"source_url":"https:\/\/gedenkstaette-vaihingen.de\/wp-content\/uploads\/2022\/05\/8-scaled.jpg","_links":{"self":[{"href":"https:\/\/gedenkstaette-vaihingen.de\/pl\/wp-json\/wp\/v2\/media\/3218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gedenkstaette-vaihingen.de\/pl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/gedenkstaette-vaihingen.de\/pl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/gedenkstaette-vaihingen.de\/pl\/wp-json\/wp\/v2\/users\/1"}]}}